{"id":11162,"date":"2024-06-20T08:32:05","date_gmt":"2024-06-20T08:32:05","guid":{"rendered":"https:\/\/www.blsgroup.com\/?p=11162"},"modified":"2024-06-25T12:53:16","modified_gmt":"2024-06-25T12:53:16","slug":"sailing-into-the-future","status":"publish","type":"post","link":"https:\/\/www.blsgroup.com\/es\/sailing-into-the-future\/","title":{"rendered":"Sailing into the future"},"content":{"rendered":"<h2 style=\"text-align: left;\"><i>\u00a0Navigare verso il futuro<\/i><\/h2>\n<hr \/>\n<p><strong>L'evento sull'innovazione, la sostenibilit\u00e0 e la sicurezza delle vie respiratorie con Giovanni Soldini<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>Il 6 giugno, a Viareggio, si \u00e8 svolto l'<strong>evento organizzato da BLS<\/strong> in collaborazione con il partner <a href=\"https:\/\/www.unigum.it\/\"><strong>Unigum<\/strong><\/a>, dedicato al <strong>futuro<\/strong>. Un futuro che, prima ancora della nostra salute, deve basarsi sulla <strong>salute del nostro pianeta<\/strong>.<\/p>\n<p>&nbsp;<\/p>\n<p>Oggi, pi\u00f9 che mai, <strong>investire nella salute ambientale significa investire nella nostra stessa sopravvivenza<\/strong>. Un ambiente sano non \u00e8 solo uno sfondo piacevole per la nostra esistenza, ma il fulcro di ogni aspetto della nostra vita quotidiana e dell'economia globale. Le risorse naturali, fondamentali per la sopravvivenza umana, sono cruciali anche per la crescita delle aziende. Questo \u00e8 particolarmente chiaro a chi lavora nella <strong>cantieristica navale<\/strong>, <span class=\"TextRun SCXW125630410 BCX0\" lang=\"IT-IT\" xml:lang=\"IT-IT\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW125630410 BCX0\" data-ccp-parastyle=\"Normal (Web)\"><span class=\"TextRun SCXW163203287 BCX0\" lang=\"IT-IT\" xml:lang=\"IT-IT\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW163203287 BCX0\" data-ccp-parastyle=\"Normal (Web)\"><span class=\"EOP SCXW18775542 BCX0\" data-ccp-props=\"{&quot;134233117&quot;:false,&quot;134233118&quot;:false,&quot;201341983&quot;:0,&quot;335559738&quot;:0,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">settore a cui era principalmente dedicato l'evento<\/span><\/span><\/span><\/span><\/span>.<\/p>\n<p>Chi lavora a stretto contatto con il mare sa bene quanto siano fondamentali <strong>biodiversit\u00e0 ed ecosistemi intatti<\/strong> per mantenere l'equilibrio del nostro pianeta. Questa consapevolezza ci deve far riflettere sull'importanza di parlare di innovazione e sviluppo sostenibile.<\/p>\n<h4><em>La tutela dell'ambiente non \u00e8 un'opzione, ma una necessit\u00e0 imprescindibile.<\/em><\/h4>\n<p>Questo impegno richiede <strong>visione, innovazione e azioni concrete<\/strong>, ma i benefici sono inestimabili, sia per noi che per le future generazioni.<\/p>\n<p>Per intraprendere questo percorso virtuoso, BLS si ispira a <strong>pionieri dell'innovazione sostenibile<\/strong>, capaci di offrire consigli preziosi basati su esperienze concrete, come il nostro partner <strong>Giovanni Soldini<\/strong>.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-11207 aligncenter\" src=\"https:\/\/www.blsgroup.com\/wp-content\/uploads\/2024\/06\/bjh-compressed.jpg\" alt=\"\" width=\"705\" height=\"496\" srcset=\"https:\/\/www.blsgroup.com\/wp-content\/uploads\/2024\/06\/bjh-compressed.jpg 1500w, https:\/\/www.blsgroup.com\/wp-content\/uploads\/2024\/06\/bjh-compressed-300x211.jpg 300w, https:\/\/www.blsgroup.com\/wp-content\/uploads\/2024\/06\/bjh-compressed-1024x720.jpg 1024w, https:\/\/www.blsgroup.com\/wp-content\/uploads\/2024\/06\/bjh-compressed-768x540.jpg 768w, https:\/\/www.blsgroup.com\/wp-content\/uploads\/2024\/06\/bjh-compressed-18x12.jpg 18w\" sizes=\"auto, (max-width: 705px) 100vw, 705px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>Il rinomato campione di vela oceanica \u00e8 stato l'ospite d'onore dell'evento e ha condiviso aneddoti e storie riguardo al suo impegno per la <strong>salvaguardia dell'ambiente marino<\/strong>.<\/p>\n<p>Una delle esperienze raccontate \u00e8 stata la traversata con il suo trimarano full electric, spiegando che \u00e8 possibile <strong>attraversare gli oceani con un impatto ambientale minimo,<\/strong> sfruttando energia pulita e rinnovabile. Questa impresa non \u00e8 solo un record sportivo, ma un messaggio potente per il mondo imprenditoriale: <strong>l'innovazione tecnologica pu\u00f2 andare di pari passo con il rispetto per l'ambiente<\/strong>. Inoltre, Soldini ha raccontato dei viaggi intorno al mondo con il suo equipaggio compiuti per <strong>raccogliere dati cruciali sulla salute dei mari<\/strong>, contribuendo cos\u00ec alla ricerca scientifica e alla consapevolezza ambientale. La sua figura di ambasciatore per la salvaguardia degli oceani dimostra come le aziende possano unire la passione per il proprio lavoro con la responsabilit\u00e0 verso il pianeta.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-11208 aligncenter\" src=\"https:\/\/www.blsgroup.com\/wp-content\/uploads\/2024\/06\/hv-compressed.jpg\" alt=\"\" width=\"536\" height=\"377\" srcset=\"https:\/\/www.blsgroup.com\/wp-content\/uploads\/2024\/06\/hv-compressed.jpg 1500w, https:\/\/www.blsgroup.com\/wp-content\/uploads\/2024\/06\/hv-compressed-300x211.jpg 300w, https:\/\/www.blsgroup.com\/wp-content\/uploads\/2024\/06\/hv-compressed-1024x720.jpg 1024w, https:\/\/www.blsgroup.com\/wp-content\/uploads\/2024\/06\/hv-compressed-768x540.jpg 768w, https:\/\/www.blsgroup.com\/wp-content\/uploads\/2024\/06\/hv-compressed-18x12.jpg 18w\" sizes=\"auto, (max-width: 536px) 100vw, 536px\" \/><\/p>\n<p>Giovanni Soldini \u00e8 un esempio di <strong>successo imprenditoriale<\/strong> non solo grazie al suo talento e alla sua esperienza, ma anche per la sua attenzione all'innovazione e l'impegno per la sicurezza ambientale e delle persone con cui lavora.<br \/>\nCoinvolgere Soldini \u00e8 stato fondamentale per noi, poich\u00e9 il suo approccio all'innovazione, che combina performance e sostenibilit\u00e0, \u00e8 un modello per le <strong>aziende che aspirano a essere competitive senza compromettere l'integrit\u00e0 dell'ambiente<\/strong>. La sua visione e le sue realizzazioni sono un punto di riferimento per chiunque voglia fare impresa in maniera consapevole e rispettosa del mondo in cui viviamo.<\/p>\n<p>Oltre all'intervento di Soldini l'evento ha trattato argomenti relativi alle <strong>normative e alla sicurezza sul lavoro<\/strong> insieme all'avvocato Claudia Del Re che ha spiegato l'importanza della protezione individuale sul luogo di lavoro e di tutte le leggi ca tutela degli operatori, soprattutto per quanto riguarda i lavoratori marittimi.<\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-11206 aligncenter\" src=\"https:\/\/www.blsgroup.com\/wp-content\/uploads\/2024\/06\/MG_8193-Edit-copia-compressed-1.jpg\" alt=\"\" width=\"657\" height=\"438\" srcset=\"https:\/\/www.blsgroup.com\/wp-content\/uploads\/2024\/06\/MG_8193-Edit-copia-compressed-1.jpg 1500w, https:\/\/www.blsgroup.com\/wp-content\/uploads\/2024\/06\/MG_8193-Edit-copia-compressed-1-300x200.jpg 300w, https:\/\/www.blsgroup.com\/wp-content\/uploads\/2024\/06\/MG_8193-Edit-copia-compressed-1-1024x683.jpg 1024w, https:\/\/www.blsgroup.com\/wp-content\/uploads\/2024\/06\/MG_8193-Edit-copia-compressed-1-768x512.jpg 768w, https:\/\/www.blsgroup.com\/wp-content\/uploads\/2024\/06\/MG_8193-Edit-copia-compressed-1-18x12.jpg 18w\" sizes=\"auto, (max-width: 657px) 100vw, 657px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p><strong>BLS<\/strong> ha avuto inoltre modo di esporre come l'azienda crede e investe nei valori di innovazione e sostenibilit\u00e0 attraverso la sua <strong>gamma di prodotti sostenibili<\/strong> che contribuiscono concretamente a un cambiamento effettivo, perch\u00e9 \u00e8 arrivato il momento in cui<em> pensare differente<\/em> non basta, bisogna anche <em><strong>agire differente<\/strong>\u00a0<\/em>per la protezione della nostra salute e di quella del nostro pianeta.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-9896 aligncenter\" src=\"https:\/\/www.blsgroup.com\/wp-content\/uploads\/2023\/12\/CLAIM_BLS-GREEN-PROJECT_2024.png\" alt=\"\" width=\"449\" height=\"225\" srcset=\"https:\/\/www.blsgroup.com\/wp-content\/uploads\/2023\/12\/CLAIM_BLS-GREEN-PROJECT_2024.png 849w, https:\/\/www.blsgroup.com\/wp-content\/uploads\/2023\/12\/CLAIM_BLS-GREEN-PROJECT_2024-300x150.png 300w, https:\/\/www.blsgroup.com\/wp-content\/uploads\/2023\/12\/CLAIM_BLS-GREEN-PROJECT_2024-768x384.png 768w, https:\/\/www.blsgroup.com\/wp-content\/uploads\/2023\/12\/CLAIM_BLS-GREEN-PROJECT_2024-18x9.png 18w\" sizes=\"auto, (max-width: 449px) 100vw, 449px\" \/><\/p>\n<div class=\"page\" title=\"Page 6\">\n<div class=\"section\">\n<div class=\"layoutArea\">\n<div class=\"column\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n<p>&nbsp;<\/p>\n<h6><em><span style=\"color: #999999;\">Resta informato<\/span><\/em><\/h6>\n<h6><em><span style=\"color: #999999;\">Resta al sicuro.<\/span><\/em><\/h6>\n<hr \/>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-3419 alignnone\" src=\"https:\/\/www.blsgroup.com\/wp-content\/uploads\/2021\/10\/CLAIM.jpg\" alt=\"\" width=\"227\" height=\"135\" srcset=\"https:\/\/www.blsgroup.com\/wp-content\/uploads\/2021\/10\/CLAIM.jpg 208w, https:\/\/www.blsgroup.com\/wp-content\/uploads\/2021\/10\/CLAIM-18x12.jpg 18w\" sizes=\"auto, (max-width: 227px) 100vw, 227px\" \/><\/p>","protected":false},"excerpt":{"rendered":"<p>\u00a0Navigare verso il futuro L'evento sull'innovazione, la sostenibilit\u00e0 e la sicurezza delle vie respiratorie con Giovanni Soldini &nbsp; Il 6 giugno, a Viareggio, si \u00e8 svolto l'evento organizzato da BLS in collaborazione con il partner Unigum, dedicato al futuro. Un futuro che, prima ancora della nostra salute, deve basarsi sulla salute del nostro pianeta. &nbsp; [&hellip;]<\/p>\n","protected":false},"author":6940,"featured_media":11204,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_seopress_robots_primary_cat":"none","_seopress_titles_title":"\"Navigare verso il futuro\" con Giovanni Soldini","_seopress_titles_desc":"L'evento organizzato da BLS e Unigum sull'innovazione, la sostenibilit\u00e0 e la sicurezza delle vie respiratorie con la partecipazione di Giovanni Soldini.","_seopress_robots_index":"","footnotes":""},"categories":[1,19,273],"tags":[173],"class_list":["post-11162","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-bls","category-highlighted","category-spotlight","tag-blscorporate"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.blsgroup.com\/es\/wp-json\/wp\/v2\/posts\/11162","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.blsgroup.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.blsgroup.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.blsgroup.com\/es\/wp-json\/wp\/v2\/users\/6940"}],"replies":[{"embeddable":true,"href":"https:\/\/www.blsgroup.com\/es\/wp-json\/wp\/v2\/comments?post=11162"}],"version-history":[{"count":0,"href":"https:\/\/www.blsgroup.com\/es\/wp-json\/wp\/v2\/posts\/11162\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.blsgroup.com\/es\/wp-json\/wp\/v2\/media\/11204"}],"wp:attachment":[{"href":"https:\/\/www.blsgroup.com\/es\/wp-json\/wp\/v2\/media?parent=11162"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.blsgroup.com\/es\/wp-json\/wp\/v2\/categories?post=11162"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.blsgroup.com\/es\/wp-json\/wp\/v2\/tags?post=11162"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}