{"id":10556,"date":"2024-04-16T10:01:49","date_gmt":"2024-04-16T10:01:49","guid":{"rendered":"https:\/\/www.blsgroup.com\/?p=10556"},"modified":"2024-04-22T09:14:35","modified_gmt":"2024-04-22T09:14:35","slug":"sawo-2024","status":"publish","type":"post","link":"https:\/\/www.blsgroup.com\/nl\/sawo-2024\/","title":{"rendered":"Sawo 2024"},"content":{"rendered":"<h2 style=\"text-align: left;\">BLS \u00e8 a Sawo 2024<\/h2>\n<hr \/>\n<h6>Pozna\u0144 (Polonia), 23 - 25 aprile 2024<\/h6>\n<p>BLS \u00e8 a Pozna\u0144 alla fiera internazionale per la protezione del lavoro, antincendio e di salvataggio pi\u00f9 grande per il settore SSL nell'Europa centrale e orientale.<\/p>\n<p><span style=\"color: #999999;\">Vieni a trovarci.<strong>\u00a0<\/strong>Siamo allo stand 24, padiglione 4<strong>.<\/strong><\/span><\/p>\n<p>&nbsp;<\/p>\n<p><img decoding=\"async\" class=\"aligncenter\" src=\"https:\/\/www.tempoitalia.it\/wp-content\/uploads\/2024\/01\/poznan-piazza-mercato.jpg\" alt=\"Poznan: le sorprese di una citt\u00e0 tutta da scoprire - Tempo Italia\" \/><\/p>\n<h3><\/h3>\n<h3><\/h3>\n<h3>La fiera<\/h3>\n<p>L'evento, organizzato in un ciclo biennale, \u00e8 l'occasione per presentare le ultime realizzazioni dei produttori polacchi e stranieri di attrezzature per la sicurezza, la salute e la protezione del lavoro.<\/p>\n<div class=\"flex-1 overflow-hidden\">\n<div class=\"react-scroll-to-bottom--css-lpuwb-79elbk h-full\">\n<div class=\"react-scroll-to-bottom--css-lpuwb-1n7m0yu\">\n<div>\n<div class=\"flex flex-col text-sm pb-9\">\n<div class=\"w-full text-token-text-primary\" dir=\"auto\" data-testid=\"conversation-turn-3\">\n<div class=\"px-4 py-2 justify-center text-base md:gap-6 m-auto\">\n<div class=\"flex flex-1 text-base mx-auto gap-3 juice:gap-4 juice:md:gap-6 md:px-5 lg:px-1 xl:px-5 md:max-w-3xl lg:max-w-[40rem] xl:max-w-[48rem] group final-completion\">\n<div class=\"relative flex w-full flex-col agent-turn\">\n<div class=\"flex-col gap-1 md:gap-3\">\n<div class=\"flex flex-grow flex-col max-w-full\">\n<div class=\"min-h-[20px] text-message flex flex-col items-start gap-3 whitespace-pre-wrap break-words [.text-message+&amp;]:mt-5 overflow-x-auto\" dir=\"auto\" data-message-author-role=\"assistant\" data-message-id=\"d27bb4e5-1880-4427-8b60-ff0560f42f36\">\n<div class=\"markdown prose w-full break-words dark:prose-invert dark\">\n<p>La Fiera Sawo non \u00e8 soltanto un evento espositivo, ma anche uno <strong>spazio per presentare tecnologie avanzate nel soccorso specialistico e nella sicurezza sul lavoro<\/strong>. I visitatori possono partecipare a convegni tematici e spettacoli, contribuendo cos\u00ec all'introduzione di soluzioni innovative nelle imprese e migliorando la qualit\u00e0 del lavoro e la sicurezza dei dipendenti. Grazie ai suoi incontri pratici e alla promozione delle buone pratiche, Sawo \u00e8 considerato un <strong>punto di riferimento nel campo della sicurezza sul lavoro e delle soluzioni ergonomiche<\/strong>.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<h4><span style=\"color: #999999;\">BLS sar\u00e0 presente tra gli espositori della fiera come produttori di dispositivi di protezione respiratoria.<\/span><\/h4>\n<hr \/>\n<p>Unisciti a noi presso <strong>MTP Pozna\u0144 Expo<\/strong>, <strong>da marted\u00ec 23 a gioved\u00ec 25 aprile, Stand 24 - Padiglione 4.<\/strong><\/p>\n<p>&nbsp;<\/p>\n<h4 style=\"text-align: center;\"><a href=\"https:\/\/targisawo.pl\/en\/\">Per scoprire di pi\u00f9 su Sawo Fair visita il sito<\/a><\/h4>\n<h6><\/h6>\n<h6><\/h6>\n<h6><span style=\"color: #808080;\"><em>Vieni a trovarci, ti aspettiamo.<\/em><\/span><\/h6>\n<p><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-3419 alignnone\" src=\"https:\/\/www.blsgroup.com\/wp-content\/uploads\/2021\/10\/CLAIM.jpg\" alt=\"\" width=\"227\" height=\"135\" srcset=\"https:\/\/www.blsgroup.com\/wp-content\/uploads\/2021\/10\/CLAIM.jpg 208w, https:\/\/www.blsgroup.com\/wp-content\/uploads\/2021\/10\/CLAIM-18x12.jpg 18w\" sizes=\"auto, (max-width: 227px) 100vw, 227px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>BLS \u00e8 a Sawo 2024 Pozna\u0144 (Polonia), 23 - 25 aprile 2024 BLS \u00e8 a Pozna\u0144 alla fiera internazionale per la protezione del lavoro, antincendio e di salvataggio pi\u00f9 grande per il settore SSL nell'Europa centrale e orientale. Vieni a trovarci.\u00a0Siamo allo stand 24, padiglione 4. &nbsp; La fiera L'evento, organizzato in un ciclo biennale, [&hellip;]<\/p>\n","protected":false},"author":6940,"featured_media":10632,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_seopress_robots_primary_cat":"none","_seopress_titles_title":"BLS \u00e8 a Sawo 2024! Vieni a trovarci allo stand 24, padiglione 4.","_seopress_titles_desc":"BLS \u00e8 a Sawo 2024, l'evento internazionale in Polonia dedicato alla sicurezza sul lavoro. Vieni a trovarci allo stand 24, dal 23 al 25 aprile.","_seopress_robots_index":"","footnotes":""},"categories":[220,19,273],"tags":[81,113,39],"class_list":["post-10556","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-bls-events","category-highlighted","category-spotlight","tag-blsevents","tag-blsexhibitions","tag-blsgroup"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.blsgroup.com\/nl\/wp-json\/wp\/v2\/posts\/10556","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.blsgroup.com\/nl\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.blsgroup.com\/nl\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.blsgroup.com\/nl\/wp-json\/wp\/v2\/users\/6940"}],"replies":[{"embeddable":true,"href":"https:\/\/www.blsgroup.com\/nl\/wp-json\/wp\/v2\/comments?post=10556"}],"version-history":[{"count":0,"href":"https:\/\/www.blsgroup.com\/nl\/wp-json\/wp\/v2\/posts\/10556\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.blsgroup.com\/nl\/wp-json\/wp\/v2\/media\/10632"}],"wp:attachment":[{"href":"https:\/\/www.blsgroup.com\/nl\/wp-json\/wp\/v2\/media?parent=10556"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.blsgroup.com\/nl\/wp-json\/wp\/v2\/categories?post=10556"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.blsgroup.com\/nl\/wp-json\/wp\/v2\/tags?post=10556"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}